{"id":115163,"date":"2026-07-15T07:57:00","date_gmt":"2026-07-15T05:57:00","guid":{"rendered":"https:\/\/www.siracusa2000.com\/?p=115163"},"modified":"2026-07-15T08:32:14","modified_gmt":"2026-07-15T06:32:14","slug":"siracusa-rinasce-la-sezione-territoriale-dellopera-nazionale-per-i-caduti-senza-croce","status":"publish","type":"post","link":"https:\/\/www.siracusa2000.com\/index.php\/2026\/07\/15\/siracusa-rinasce-la-sezione-territoriale-dellopera-nazionale-per-i-caduti-senza-croce\/","title":{"rendered":"Siracusa. Rinasce la sezione territoriale dell\u2019Opera Nazionale per i Caduti senza Croce"},"content":{"rendered":"\n<p>\u00a0\u00c8 stata ricostituita a <strong>Siracusa<\/strong> la Sezione territoriale dell&#8217;<strong>O.N.C.s.C &#8211; Opera Nazionale per i Caduti senza Croce<\/strong>, storica associazione che da oltre sessant&#8217;anni opera per custodire la memoria di quanti hanno sacrificato la propria vita senza avere una tomba, una lapide o un luogo in cui essere ricordati.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"614\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2026\/07\/IMG-20260710-WA0247-1024x614.jpg\" alt=\"\" class=\"wp-image-115164\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2026\/07\/IMG-20260710-WA0247-1024x614.jpg 1024w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2026\/07\/IMG-20260710-WA0247-300x180.jpg 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2026\/07\/IMG-20260710-WA0247-768x460.jpg 768w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2026\/07\/IMG-20260710-WA0247.jpg 1056w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Presidente e vicepresidente saranno rispettivamente <strong>Alessandro Maiolino<\/strong> ed <strong>Alberto Moscuzza<\/strong>;  la carica di segretario sar\u00e0 ricoperta da <strong>Francesco Saverio Paci<\/strong>, mentre <strong>Tiziana Vitanza <\/strong>curer\u00e0 le Pubbliche Relazioni.<\/p>\n\n\n\n<p>L&#8217;<strong>Opera Nazionale per i Caduti senza Croce<\/strong> \u00e8 un Ente apolitico e apartitico che fonda la propria missione sul dovere della memoria, promuovendo la ricerca storica, la divulgazione culturale e le iniziative commemorative, con particolare attenzione al coinvolgimento delle nuove generazioni.<\/p>\n\n\n\n<p>La ricostituzione della Sezione di <strong>Siracusa<\/strong> testimonia l&#8217;impegno dell&#8217;<strong>Opera Nazionale per i Caduti senza Croce<\/strong> nel mantenere vivo il ricordo di chi ha sacrificato la propria vita, facendo della memoria un autentico strumento di educazione alla pace e di dialogo tra le generazioni.<\/p>\n\n\n\n<p>(foto: il direttivo)<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>\u00a9 Riproduzione riservata<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"926\" height=\"419\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend.png\" alt=\"\" class=\"wp-image-55152\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend.png 926w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend-300x136.png 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend-768x348.png 768w\" sizes=\"auto, (max-width: 926px) 100vw, 926px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00c8 stata ricostituita a Siracusa la Sezione territoriale dell&#8217;O.N.C.s.C &#8211; Opera Nazionale per i Caduti senza Croce, storica associazione che da oltre sessant&#8217;anni opera per custodire la memoria di quanti hanno sacrificato la propria vita senza avere una tomba, una <a href=\"https:\/\/www.siracusa2000.com\/index.php\/2026\/07\/15\/siracusa-rinasce-la-sezione-territoriale-dellopera-nazionale-per-i-caduti-senza-croce\/\" class=\"read-more\">Leggi Tutto &#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":115164,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-115163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-citta"],"_links":{"self":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/115163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/comments?post=115163"}],"version-history":[{"count":1,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/115163\/revisions"}],"predecessor-version":[{"id":115165,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/115163\/revisions\/115165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media\/115164"}],"wp:attachment":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media?parent=115163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/categories?post=115163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/tags?post=115163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}