{"id":65493,"date":"2022-01-28T12:09:19","date_gmt":"2022-01-28T11:09:19","guid":{"rendered":"https:\/\/www.siracusa2000.com\/?p=65493"},"modified":"2022-01-28T12:09:22","modified_gmt":"2022-01-28T11:09:22","slug":"enti-locali-il-csa-incontra-gli-amministratori-applicare-le-progressioni-per-tutti-i-lavoratori","status":"publish","type":"post","link":"https:\/\/www.siracusa2000.com\/index.php\/2022\/01\/28\/enti-locali-il-csa-incontra-gli-amministratori-applicare-le-progressioni-per-tutti-i-lavoratori\/","title":{"rendered":"Enti Locali. Il CSA incontra gli amministratori, applicare le progressioni per tutti i lavoratori"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"824\" height=\"512\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/01\/ufficio_pubblico.jpg\" alt=\"\" class=\"wp-image-65494\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/01\/ufficio_pubblico.jpg 824w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/01\/ufficio_pubblico-300x186.jpg 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/01\/ufficio_pubblico-768x477.jpg 768w\" sizes=\"auto, (max-width: 824px) 100vw, 824px\" \/><\/figure>\n\n\n\n<p>L e problematiche del personale degli Enti Locali sono al centro di una serie di incontri che la segreteria provinciale del <strong>CSA<\/strong> sta tenendo, in queste settimane, con i rappresentanti delle Pubbliche Amministrazioni del territorio.<\/p>\n\n\n\n<p>In un momento di grande fermento per gli Enti, da un lato alle prese con i disagi causati dai contagi che bloccano i servizi, costringendo alla chiusura degli uffici, dall\u2019altro con l\u2019imminente rivoluzione digitale che richieder\u00e0 specifiche formazioni professionali per il personale, la tutela dei diritti dei dipendenti diventa,\u00a0 pi\u00f9 che mai, importante.<\/p>\n\n\n\n<p>\u201cE\u2019 nostra intenzione\u201d \u2013 si legge nel documento \u2013 \u201cverificare l\u2019esatta applicazione delle normative relative alle progressioni orizzontali\u00a0 e verticali, soprattutto per i lavoratori di categoria B. Si tratta, infatti, della fascia pi\u00f9 consistente negli organici\u201d \u2013 sottolinea il <strong>CSA provinciale<\/strong> \u2013 \u201cche, nonostante, l\u2019essenzialit\u00e0 della propria attivit\u00e0 all\u2019interno delle Amministrazioni, spesso non viene gratificata cos\u00ec come meriterebbe\u201d.<\/p>\n\n\n\n<p>I rappresentanti della segreteria provinciale della sigla sindacale giudicano in maniera positiva la disponibilit\u00e0 al dialogo manifestata dai rappresentanti dei comuni con i quali si sono gi\u00e0 incontrati, l\u2019ultimo dei quali, il neo <strong>sindaco di Noto, Corrado Figura<\/strong>, il quale, conclude la nota \u201c\u00e8 disponibilissimo ad affrontare l\u2019argomento\u201d.<\/p>\n\n\n\n<p><em>(foto: repertorio internet)<\/em><\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>\u00a9 Riproduzione riservata<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"572\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/06\/banner-dance-dance-1.png\" alt=\"\" class=\"wp-image-57414\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/06\/banner-dance-dance-1.png 853w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/06\/banner-dance-dance-1-300x201.png 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/06\/banner-dance-dance-1-768x515.png 768w\" sizes=\"auto, (max-width: 853px) 100vw, 853px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>L e problematiche del personale degli Enti Locali sono al centro di una serie di incontri che la segreteria provinciale del CSA sta tenendo, in queste settimane, con i rappresentanti delle Pubbliche Amministrazioni del territorio. In un momento di grande <a href=\"https:\/\/www.siracusa2000.com\/index.php\/2022\/01\/28\/enti-locali-il-csa-incontra-gli-amministratori-applicare-le-progressioni-per-tutti-i-lavoratori\/\" class=\"read-more\">Leggi Tutto &#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":65494,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-65493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"_links":{"self":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/65493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/comments?post=65493"}],"version-history":[{"count":1,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/65493\/revisions"}],"predecessor-version":[{"id":65495,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/65493\/revisions\/65495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media\/65494"}],"wp:attachment":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media?parent=65493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/categories?post=65493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/tags?post=65493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}