{"id":65788,"date":"2022-02-08T11:54:25","date_gmt":"2022-02-08T10:54:25","guid":{"rendered":"https:\/\/www.siracusa2000.com\/?p=65788"},"modified":"2022-02-08T11:54:28","modified_gmt":"2022-02-08T10:54:28","slug":"comiso-vandalizzata-la-casa-rurale-del-parco-dellippari-indignazione-del-sindaco","status":"publish","type":"post","link":"https:\/\/www.siracusa2000.com\/index.php\/2022\/02\/08\/comiso-vandalizzata-la-casa-rurale-del-parco-dellippari-indignazione-del-sindaco\/","title":{"rendered":"Comiso. Vandalizzata la casa rurale del parco dell&#8217;Ippari, indignazione del sindaco"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"713\" height=\"508\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/02\/comiso-1.jpg\" alt=\"\" class=\"wp-image-65789\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/02\/comiso-1.jpg 713w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/02\/comiso-1-300x214.jpg 300w\" sizes=\"auto, (max-width: 713px) 100vw, 713px\" \/><\/figure><\/div>\n\n\n\n<p>Nell\u2019era del \u201cgrande fratello\u201d,con le strade delle nostre citt\u00e0,\u00a0 con le piazze ed i siti culturali che pullulano di telecamere di videosorveglianza c\u2019\u00e8 ancora chi crede di poterla fare franca, mettendo a segno atti vandalici per il solo gusto di dare sfogo alle proprie insoddisfazioni.<\/p>\n\n\n\n<p>A farne le spese, probabilmente nel fine settimana, \u00e8 stata la <strong>casa rurale<\/strong> all\u2019interno del <strong>parco dell\u2019Ippari<\/strong> a<strong> Comiso<\/strong>, le cui pareti sono state sfregiate con frasi stupide, che la dicono lunga sul livello di maturit\u00e0 del o degli autori.<\/p>\n\n\n\n<p>Gente talmente matura ed astuta da non essersi nemmeno posta il problema di una eventuale presenza di telecamere che, infatti, c\u2019erano e che hanno registrato tutto il \u201cfilm\u201d. <\/p>\n\n\n\n<p>Le immagini, adesso, sono al vaglio della <strong>Polizia di Stato<\/strong>, che sta indagando per dare un volto ed un nome agli \u201cartisti\u201d del parco.<\/p>\n\n\n\n<p>Fortemente indignata <strong>Maria Rita Schembari, <\/strong>sindaco della citt\u00e0: \u201cquanta tristezza, quanta miserabile superficialit\u00e0\u201d, \u00a0commenta, auspicando che, al pi\u00f9 presto, chi si \u00e8 reso responsabile di simili \u201caffreschi\u201d possa essere identificato e sanzionato, cosi come prevedono le leggi.<\/p>\n\n\n\n<p><em>(foto: le pareti in pietra di Comiso, imbrattate dai vandali)<\/em><\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>\u00a9 Riproduzione riservata<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"172\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2020\/10\/banner-diretta-santa-messa-1024x172.jpg\" alt=\"\" class=\"wp-image-47982\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2020\/10\/banner-diretta-santa-messa-1024x172.jpg 1024w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2020\/10\/banner-diretta-santa-messa-300x50.jpg 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2020\/10\/banner-diretta-santa-messa-768x129.jpg 768w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2020\/10\/banner-diretta-santa-messa.jpg 1030w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Nell\u2019era del \u201cgrande fratello\u201d,con le strade delle nostre citt\u00e0,\u00a0 con le piazze ed i siti culturali che pullulano di telecamere di videosorveglianza c\u2019\u00e8 ancora chi crede di poterla fare franca, mettendo a segno atti vandalici per il solo gusto di <a href=\"https:\/\/www.siracusa2000.com\/index.php\/2022\/02\/08\/comiso-vandalizzata-la-casa-rurale-del-parco-dellippari-indignazione-del-sindaco\/\" class=\"read-more\">Leggi Tutto &#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":65789,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-65788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fuori-provincia"],"_links":{"self":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/65788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/comments?post=65788"}],"version-history":[{"count":1,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/65788\/revisions"}],"predecessor-version":[{"id":65790,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/65788\/revisions\/65790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media\/65789"}],"wp:attachment":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media?parent=65788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/categories?post=65788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/tags?post=65788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}