{"id":65945,"date":"2022-02-12T18:42:04","date_gmt":"2022-02-12T17:42:04","guid":{"rendered":"https:\/\/www.siracusa2000.com\/?p=65945"},"modified":"2022-02-12T21:09:42","modified_gmt":"2022-02-12T20:09:42","slug":"feste-popolari-dal-senato-ok-allemendamento-della-lega-che-autorizza-le-processioni","status":"publish","type":"post","link":"https:\/\/www.siracusa2000.com\/index.php\/2022\/02\/12\/feste-popolari-dal-senato-ok-allemendamento-della-lega-che-autorizza-le-processioni\/","title":{"rendered":"Feste popolari. Dal Senato ok all&#8217;emendamento della Lega che autorizza le processioni"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"864\" height=\"532\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/02\/proce.png\" alt=\"\" class=\"wp-image-65946\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/02\/proce.png 864w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/02\/proce-300x185.png 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/02\/proce-768x473.png 768w\" sizes=\"auto, (max-width: 864px) 100vw, 864px\" \/><\/figure>\n\n\n\n<p>L\u2019Aula di <strong>Palazzo Madama<\/strong> ha detto s\u00ec ad un emendamento di cui \u00e8 primo firmatario il \u00a0<strong>senatore Luca Briziarelli<\/strong> della <strong>Lega<\/strong>, che autorizza lo svolgimento delle feste popolari e delle manifestazioni culturali di notevole interesse, anche quando si svolgono in modalit\u00e0 itinerante ed in forma dinamica. <\/p>\n\n\n\n<p>In pratica, l\u2019emendamento, nonostante il parere contrario del Governo, \u00a0d\u00e0 il via libera a tutte quelle processioni religiose che, da due anni, sono state sospese a causa della pandemia, e che tanto stanno mancando ai fedeli. <\/p>\n\n\n\n<p>Salvo ulteriori colpi di scena, quindi, prima dell&#8217;estate dovrebbero tornare alla normalit\u00e0 le feste del <strong>patrocinio di \u00a0Santa Lucia<\/strong> a <strong>Siracusa<\/strong>, le feste di <strong>Santa Rosalia<\/strong> a <strong>Palermo<\/strong>, di <strong>Sant\u2019Agata<\/strong> d\u2019agosto a <strong>Catania,<\/strong> di S<strong>anta Venera <\/strong>ad <strong>Acireale<\/strong> e cos\u00ec via. <\/p>\n\n\n\n<p>\u201cQuesti eventi\u201d \u2013 commenta <strong>Briziarelli <\/strong>\u2013 \u201cda nord a sud, sono il cuore e l&#8217;anima delle nostra storia e delle nostre tradizioni e rappresentano uno degli aspetti che rendono l&#8217;<strong>Italia<\/strong> unica e hanno anche una forte attrazione sul piano turistico\u201d.<\/p>\n\n\n\n<p><em>(foto: archivio siracsua2000)<\/em><\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>\u00a9 Riproduzione riservata<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"172\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2020\/10\/banner-diretta-santa-messa-1024x172.jpg\" alt=\"\" class=\"wp-image-47982\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2020\/10\/banner-diretta-santa-messa-1024x172.jpg 1024w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2020\/10\/banner-diretta-santa-messa-300x50.jpg 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2020\/10\/banner-diretta-santa-messa-768x129.jpg 768w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2020\/10\/banner-diretta-santa-messa.jpg 1030w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Aula di Palazzo Madama ha detto s\u00ec ad un emendamento di cui \u00e8 primo firmatario il \u00a0senatore Luca Briziarelli della Lega, che autorizza lo svolgimento delle feste popolari e delle manifestazioni culturali di notevole interesse, anche quando si svolgono in <a href=\"https:\/\/www.siracusa2000.com\/index.php\/2022\/02\/12\/feste-popolari-dal-senato-ok-allemendamento-della-lega-che-autorizza-le-processioni\/\" class=\"read-more\">Leggi Tutto &#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":65946,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-65945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/65945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/comments?post=65945"}],"version-history":[{"count":2,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/65945\/revisions"}],"predecessor-version":[{"id":65949,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/65945\/revisions\/65949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media\/65946"}],"wp:attachment":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media?parent=65945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/categories?post=65945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/tags?post=65945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}