{"id":73606,"date":"2022-10-10T06:28:00","date_gmt":"2022-10-10T04:28:00","guid":{"rendered":"https:\/\/www.siracusa2000.com\/?p=73606"},"modified":"2022-10-09T20:38:52","modified_gmt":"2022-10-09T18:38:52","slug":"tennistavolo-sorride-la-vi-ga-ro-siracusa-che-in-b2-e-c1-non-fa-sconti","status":"publish","type":"post","link":"https:\/\/www.siracusa2000.com\/index.php\/2022\/10\/10\/tennistavolo-sorride-la-vi-ga-ro-siracusa-che-in-b2-e-c1-non-fa-sconti\/","title":{"rendered":"Tennistavolo. Sorride la VI.GA.RO. Siracusa che in B2 e C1 non fa sconti"},"content":{"rendered":"\n<p>Dopo la rinuncia del Citt\u00e0 di Siracusa, \u00e8 la VI.GA.RO l\u2019unica societ\u00e0 a rappresentare i colori della provincia nei campionati nazionali.<\/p>\n\n\n\n<p>Dopo l\u2019inaspettato passo falso in serie B2, nel primo turno di campionato a Catania contro il Circolo Etneo impostosi per 5-4, la VI.GA.RO si riscatta ampiamente nella seconda giornata. In casa, nella palestra dell\u2019Istituto Comprensivo \u201cS. Raiti\u201d, la squadra del presidente Giuseppe Gamuzza non ha avuto problemi nel superare la Top Spin Messina Assiconsult con il netto punteggio di 5-0. Protagonisti del successo sono stati, con due doppiette ciascuno, Salvo Ganci (l\u2019atleta di maggior spicco) e il bravo Fabio Amenta (apparso quanto mai concentrato). <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1009\" height=\"586\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/10\/vigaro.png\" alt=\"\" class=\"wp-image-73607\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/10\/vigaro.png 1009w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/10\/vigaro-300x174.png 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/10\/vigaro-768x446.png 768w\" sizes=\"auto, (max-width: 1009px) 100vw, 1009px\" \/><\/figure>\n\n\n\n<p>Il bottino \u00e8 stato completato dal coriaceo Francesco Mollica, autore di una splendida prestazione contro il forte Giuseppe Quartuccio, sconfitto per 3-2. La compagine siracusana \u00e8 indicata come una delle protagoniste in chiave promozione, anche se il capitano Francesco Mollica non si sbilancia. \u201cLa battuta d\u2019arresto nella prima giornata non ci voleva, anche se le attenuanti non mancano di certo &#8211; dice Mollica. Il campionato \u00e8 lungo e pieno di incognite. Molti ci danno per favoriti, ma non \u00e8 facile; ci sono tante insidie e dovremo essere sempre pronti e non abbassare mai la guardia\u201d.<\/p>\n\n\n\n<p>Sabato prossimo ad Enna, contro l\u2019Ausonia, \u00e8 previsto il prossimo impegno di campionato; \u00e8 una trasferta da prendere con le pinze, anche per la presenza nella squadra avversaria del forte bulgaro Vasil Hristozov, ma la VI.GA.RO ha tutte le carte in regola per continuare la striscia vincente.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"317\" height=\"175\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2020\/11\/bug-spazio-italia.micro_.gif\" alt=\"\" class=\"wp-image-48472\"\/><\/figure><\/div>\n\n\n\n<p>Anche dalla serie C1 arrivano buone notizie. A Pedara, contro il Citt\u00e0 di Pedara-Il Circolo Etneo, la VI.GA.RO. detta legge, vincendo per 5-1.\u00a0 Per la squadra siracusana due punti ciascuno da parte del presidente Giuseppe Gamuzza, che come atleta \u00e8 assai ostico da superare e dal neo acquisto Francesco Pelligra (proveniente dal Robur Noto), che ha arricchito ulteriormente il bagaglio di esperienza della squadra. <\/p>\n\n\n\n<p>Utilissimo il punto conquistato da un convinto Adolfo Reale che, pian piano, sta conquistando la sua forma migliore. Gamuzza e compagni hanno tutte le credenziali per far bene anche domenica prossima, quando alle 10,30, nella palestra dell\u2019Istituto Comprensivo \u201cS.Raiti\u201d affronteranno il T.T. Vittoria 1999 (sky blue) nella terza giornata di campionato<em>.(Mario Lo Presti)<\/em><\/p>\n\n\n\n<p><em>(foto: la ViGaRo e la Top Spin Messina, da sinistra P. Briuglia, G. Quartuccio, il tecnico M. Puglisi, F. D&#8217;Antonio, l&#8217;arbitro A. Elia, F. Mollica, S. Ganci, F. Amenta)<\/em><\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>\u00a9 Riproduzione riservata<\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"159\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/08\/banner-meteo.png\" alt=\"\" class=\"wp-image-72101\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/08\/banner-meteo.png 720w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/08\/banner-meteo-300x66.png 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dopo la rinuncia del Citt\u00e0 di Siracusa, \u00e8 la VI.GA.RO l\u2019unica societ\u00e0 a rappresentare i colori della provincia nei campionati nazionali. Dopo l\u2019inaspettato passo falso in serie B2, nel primo turno di campionato a Catania contro il Circolo Etneo impostosi <a href=\"https:\/\/www.siracusa2000.com\/index.php\/2022\/10\/10\/tennistavolo-sorride-la-vi-ga-ro-siracusa-che-in-b2-e-c1-non-fa-sconti\/\" class=\"read-more\">Leggi Tutto &#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":73607,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-73606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"_links":{"self":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/73606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/comments?post=73606"}],"version-history":[{"count":1,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/73606\/revisions"}],"predecessor-version":[{"id":73609,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/73606\/revisions\/73609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media\/73607"}],"wp:attachment":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media?parent=73606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/categories?post=73606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/tags?post=73606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}