{"id":73871,"date":"2022-10-18T09:21:00","date_gmt":"2022-10-18T07:21:00","guid":{"rendered":"https:\/\/www.siracusa2000.com\/?p=73871"},"modified":"2022-10-17T20:17:27","modified_gmt":"2022-10-17T18:17:27","slug":"siracusa-terza-edizione-del-concorso-le-diverse-abilita-nel-mondo-della-ristorazione","status":"publish","type":"post","link":"https:\/\/www.siracusa2000.com\/index.php\/2022\/10\/18\/siracusa-terza-edizione-del-concorso-le-diverse-abilita-nel-mondo-della-ristorazione\/","title":{"rendered":"Siracusa. Terza edizione del concorso &#8220;Le diverse abilit\u00e0 nel mondo della ristorazione&#8221;"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"947\" height=\"613\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/10\/alberghiero.png\" alt=\"\" class=\"wp-image-73872\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/10\/alberghiero.png 947w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/10\/alberghiero-300x194.png 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/10\/alberghiero-768x497.png 768w\" sizes=\"auto, (max-width: 947px) 100vw, 947px\" \/><\/figure>\n\n\n\n<p>Prender\u00e0 il via domani, presso un noto albergo cittadino, il terzo Concorso Nazionale dell\u2019<strong>A.M.I.R.A. Associazione Maitres Italiani Ristoranti e Alberghi<\/strong>, organizzato con la collaborazione dell\u2019Amministrazione comunale di Siracusa, dell\u2019<strong>Istituto Alberghiero \u201cFederico II di Svevia<\/strong>\u201d e delle associazioni \u201c<strong>Sicilia Turismo per Tutti\u201d , \u201cMangiare bene e non solo\u201d<\/strong> e \u201c<strong>Noi Albergatori\u201d.<\/strong><\/p>\n\n\n\n<p><strong>\u201cLe diverse abilit\u00e0 nel mondo della ristorazione\u201d, <\/strong>vedr\u00e0 protagonisti i ragazzi speciali che, con la guida dei loro maestri, prepareranno le prelibatezze da far gustare alla giuria nazionale composta dal presidente, il <strong>Gran Cancelliere Claudio Recchia,<\/strong> dallo chef stellato Maurizio Urso, dalla <strong>sommelier Vilma Broggi<\/strong>, dalla giornalista <strong>Stefania Calanni<\/strong> e dalla <strong>dirigente del \u201cFederico II di Svevia\u201d, Vittoriana Accardo.<\/strong><\/p>\n\n\n\n<p>\u201cDobbiamo sempre puntare all\u2019inclusione, sotto tutti i punti di vista\u201d- dichiara <strong>Bernadette Lo Bianco, presidente di Sicilia Turismo per Tutti <\/strong>\u2013 \u201coltre alle barriere architettoniche, sensoriali e cognitive, \u00e8 necessario abbattere quelle relazionali e i pregiudizi. La diversit\u00e0\u201d \u2013 aggiunge \u2013 \u201cdeve diventare quel valore aggiunto che contribuisce alla performance efficace dell\u2019azienda\u201d.<\/p>\n\n\n\n<p>Al concorso parteciperanno al concorso squadre di <strong>Siracusa, &nbsp;Catania, Ragusa, Palermo<\/strong> e da altre regioni italiane.<\/p>\n\n\n\n<p><em>(foto: un\u2019immagine della seconda edizione del concorso)<\/em><\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>\u00a9 Riproduzione riservata<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"926\" height=\"419\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend.png\" alt=\"\" class=\"wp-image-55152\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend.png 926w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend-300x136.png 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend-768x348.png 768w\" sizes=\"auto, (max-width: 926px) 100vw, 926px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Prender\u00e0 il via domani, presso un noto albergo cittadino, il terzo Concorso Nazionale dell\u2019A.M.I.R.A. Associazione Maitres Italiani Ristoranti e Alberghi, organizzato con la collaborazione dell\u2019Amministrazione comunale di Siracusa, dell\u2019Istituto Alberghiero \u201cFederico II di Svevia\u201d e delle associazioni \u201cSicilia Turismo per <a href=\"https:\/\/www.siracusa2000.com\/index.php\/2022\/10\/18\/siracusa-terza-edizione-del-concorso-le-diverse-abilita-nel-mondo-della-ristorazione\/\" class=\"read-more\">Leggi Tutto &#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":73872,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-73871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-citta"],"_links":{"self":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/73871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/comments?post=73871"}],"version-history":[{"count":1,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/73871\/revisions"}],"predecessor-version":[{"id":73873,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/73871\/revisions\/73873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media\/73872"}],"wp:attachment":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media?parent=73871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/categories?post=73871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/tags?post=73871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}