{"id":73928,"date":"2022-10-20T06:24:00","date_gmt":"2022-10-20T04:24:00","guid":{"rendered":"https:\/\/www.siracusa2000.com\/?p=73928"},"modified":"2022-10-19T21:25:00","modified_gmt":"2022-10-19T19:25:00","slug":"siracusa-torna-la-casa-delle-farfalle-al-giardino-dellartemision-dal-9-gennaio-2023","status":"publish","type":"post","link":"https:\/\/www.siracusa2000.com\/index.php\/2022\/10\/20\/siracusa-torna-la-casa-delle-farfalle-al-giardino-dellartemision-dal-9-gennaio-2023\/","title":{"rendered":"Siracusa. Torna la &#8220;Casa delle Farfalle&#8221; al Giardino dell&#8217;Artemision, dal 9 gennaio 2023"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"982\" height=\"545\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/10\/mostra.png\" alt=\"\" class=\"wp-image-73929\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/10\/mostra.png 982w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/10\/mostra-300x166.png 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/10\/mostra-768x426.png 768w\" sizes=\"auto, (max-width: 982px) 100vw, 982px\" \/><\/figure>\n\n\n\n<p>A gennaio, nel<strong> Giardino dell\u2019Artemision<\/strong>, in <strong>piazza Minerva<\/strong>, torner\u00e0 la \u201c<strong>Casa delle Farfalle\u201d, <\/strong>iniziativa che, nel 2018, ha registrato un \u00a0grande successo di pubblico. <\/p>\n\n\n\n<p>A differenza di 4 anni fa, stavolta, la mostra rester\u00e0 tre mesi in pi\u00f9, dal 9 gennaio al 30 giugno. Sar\u00e0 creato un ambiente tropicale, con piante e umidit\u00e0 controllata, dove farfalle di tutte le dimensioni, variopinte e provenienti da altri continenti potranno svolgere il loro ciclo vitale sotto gli occhi dei visitatori.<\/p>\n\n\n\n<p>\u201cSar\u00e0 possibile assistere alla nascita di una farfalla\u201d \u2013 dichiara il <strong>sindaco Francesco Italia<\/strong> \u2013 \u201cal primo volo una volta dispiegate le ali e vederle mentre si riposano o si nutrono\u201d. <\/p>\n\n\n\n<p>Previsti biglietti a prezzo ridotto per le scolaresche ed ingressi gratuiti per i bambini fino a 30 mesi di et\u00e0.<\/p>\n\n\n\n<p><em>(foto: repertorio internet)<\/em><\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>\u00a9 Riproduzione riservata<\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"579\" height=\"197\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/10\/bug-spazio-italia.gif\" alt=\"\" class=\"wp-image-73464\"\/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A gennaio, nel Giardino dell\u2019Artemision, in piazza Minerva, torner\u00e0 la \u201cCasa delle Farfalle\u201d, iniziativa che, nel 2018, ha registrato un \u00a0grande successo di pubblico. A differenza di 4 anni fa, stavolta, la mostra rester\u00e0 tre mesi in pi\u00f9, dal 9 <a href=\"https:\/\/www.siracusa2000.com\/index.php\/2022\/10\/20\/siracusa-torna-la-casa-delle-farfalle-al-giardino-dellartemision-dal-9-gennaio-2023\/\" class=\"read-more\">Leggi Tutto &#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":73929,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-73928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-citta"],"_links":{"self":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/73928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/comments?post=73928"}],"version-history":[{"count":1,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/73928\/revisions"}],"predecessor-version":[{"id":73930,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/73928\/revisions\/73930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media\/73929"}],"wp:attachment":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media?parent=73928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/categories?post=73928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/tags?post=73928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}