{"id":73980,"date":"2022-10-20T20:46:13","date_gmt":"2022-10-20T18:46:13","guid":{"rendered":"https:\/\/www.siracusa2000.com\/?p=73980"},"modified":"2022-10-20T20:46:15","modified_gmt":"2022-10-20T18:46:15","slug":"maletto-conoscere-e-combattere-lendometriosi-il-28-ottobre-un-incontro-nellaula-consiliare","status":"publish","type":"post","link":"https:\/\/www.siracusa2000.com\/index.php\/2022\/10\/20\/maletto-conoscere-e-combattere-lendometriosi-il-28-ottobre-un-incontro-nellaula-consiliare\/","title":{"rendered":"Maletto. Conoscere e combattere l\u2019endometriosi, il 28 ottobre un incontro nell\u2019aula consiliare"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"942\" height=\"581\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/10\/endometriosi.png\" alt=\"\" class=\"wp-image-73981\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/10\/endometriosi.png 942w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/10\/endometriosi-300x185.png 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/10\/endometriosi-768x474.png 768w\" sizes=\"auto, (max-width: 942px) 100vw, 942px\" \/><\/figure>\n\n\n\n<p><strong>&#8220;Sediamoci sul giallo: endopank<\/strong>\u201d \u00e8 il titolo di un incontro che si terr\u00e0 venerd\u00ec 28 ottobre alle ore 10, nell\u2019aula consiliare del <strong>Comune di Maletto,<\/strong> per promuovere e sensibilizzare la prevenzione dell\u2019endometriosi.<\/p>\n\n\n\n<p>Circa 3 milioni, in I<strong>talia<\/strong>, le persone affette da questa patologia altamente invalidante che bisogna, necessariamente, imparare a riconoscere per poterla combattere.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Ed \u00e8 proprio questo l\u2019obiettivo del progetto<em> \u201c<\/em><strong>Endopank<\/strong><em>\u201d<\/em> e dell\u2019incontro del 28 ottobre, organizzato insieme alla <strong>dott.ssa Sabrina Schilir\u00f2<\/strong> e alla referente dell\u2019associazione <strong>\u201c<\/strong>La voce di una \u00e8 la voce di tutte&#8221;, <strong>Laura Franco<\/strong>, che interverranno insieme al sindaco <strong>Giuseppe De Luca<\/strong>.<\/p>\n\n\n\n<p><strong> <\/strong>Al termine dell\u2019incontro, in <strong>piazza XXIV Maggio<\/strong>, avr\u00e0 luogo la cerimonia di inaugurazione della panchina gialla. Il colore giallo rappresenta, infatti, questa dura malattia.<\/p>\n\n\n\n<p><em>(foto: repertorio internet)<\/em><\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>\u00a9 Riproduzione riservata<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"926\" height=\"419\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend.png\" alt=\"\" class=\"wp-image-55152\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend.png 926w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend-300x136.png 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend-768x348.png 768w\" sizes=\"auto, (max-width: 926px) 100vw, 926px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Sediamoci sul giallo: endopank\u201d \u00e8 il titolo di un incontro che si terr\u00e0 venerd\u00ec 28 ottobre alle ore 10, nell\u2019aula consiliare del Comune di Maletto, per promuovere e sensibilizzare la prevenzione dell\u2019endometriosi. Circa 3 milioni, in Italia, le persone affette <a href=\"https:\/\/www.siracusa2000.com\/index.php\/2022\/10\/20\/maletto-conoscere-e-combattere-lendometriosi-il-28-ottobre-un-incontro-nellaula-consiliare\/\" class=\"read-more\">Leggi Tutto &#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":73981,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-73980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fuori-provincia"],"_links":{"self":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/73980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/comments?post=73980"}],"version-history":[{"count":1,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/73980\/revisions"}],"predecessor-version":[{"id":73982,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/73980\/revisions\/73982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media\/73981"}],"wp:attachment":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media?parent=73980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/categories?post=73980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/tags?post=73980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}