{"id":76438,"date":"2022-12-28T06:19:00","date_gmt":"2022-12-28T05:19:00","guid":{"rendered":"https:\/\/www.siracusa2000.com\/?p=76438"},"modified":"2022-12-27T21:29:56","modified_gmt":"2022-12-27T20:29:56","slug":"catania-trasporto-alunni-disabili-presentazione-domande-contributo-entro-il-18-gennaio","status":"publish","type":"post","link":"https:\/\/www.siracusa2000.com\/index.php\/2022\/12\/28\/catania-trasporto-alunni-disabili-presentazione-domande-contributo-entro-il-18-gennaio\/","title":{"rendered":"Catania. Trasporto alunni disabili, presentazione domande contributo entro il 18 gennaio"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"995\" height=\"560\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/12\/screenshot-232.png\" alt=\"\" class=\"wp-image-76439\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/12\/screenshot-232.png 995w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/12\/screenshot-232-300x169.png 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/12\/screenshot-232-768x432.png 768w\" sizes=\"auto, (max-width: 995px) 100vw, 995px\" \/><\/figure>\n\n\n\n<p>Potranno essere presentate entro e non oltre il 18 gennaio 2023, attraverso la piattaforma &#8220;<strong>Catania Semplice&#8221;<\/strong>, all\u2019interno del sito istituzionale del <strong>Comune di Catania<\/strong>, le domande per l\u2019ottenimento del contributo per il trasporto scolastico degli alunni con disabilit\u00e0.<\/p>\n\n\n\n<p>Beneficiarie sono le famiglie di studenti che siano residenti a <strong>Catania<\/strong>, con certificazione ISEE pari o inferiore a 25 mila euro.<\/p>\n\n\n\n<p>Altro requisito indispensabile \u00e8 che gli studenti frequentino o abbiano frequentato la scuola dell&#8217;infanzia, la scuola primaria e la scuola secondaria di primo grado nell\u2019anno solare 2022.<br>Il contributo una tantum verr\u00e0 assegnato al nucleo familiare che sceglie di trasportare autonomamente il minore disabile e sar\u00e0 attribuito in base al numero delle istanze che verranno presentate e comunque fino a esaurimento delle risorse ministeriali.<\/p>\n\n\n\n<p>Il bando e lo schema di domanda sono disponibili alla voce \u201cAvvisi\u201d del sito istituzionale del Comune.Di seguito il link:<\/p>\n\n\n\n<p><a href=\"https:\/\/www.comune.catania.it\/informazioni\/avvisi\/default.aspx?news=86136\">https:\/\/www.comune.catania.it\/informazioni\/avvisi\/default.aspx?news=86136<\/a><\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>(foto: repertorio internet)<\/em><\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>\u00a9 Riproduzione riservata<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"175\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/05\/banner-webtv-webradio-1-1024x175.png\" alt=\"\" class=\"wp-image-56578\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/05\/banner-webtv-webradio-1-1024x175.png 1024w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/05\/banner-webtv-webradio-1-300x51.png 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/05\/banner-webtv-webradio-1-768x131.png 768w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/05\/banner-webtv-webradio-1.png 1112w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Potranno essere presentate entro e non oltre il 18 gennaio 2023, attraverso la piattaforma &#8220;Catania Semplice&#8221;, all\u2019interno del sito istituzionale del Comune di Catania, le domande per l\u2019ottenimento del contributo per il trasporto scolastico degli alunni con disabilit\u00e0. Beneficiarie sono <a href=\"https:\/\/www.siracusa2000.com\/index.php\/2022\/12\/28\/catania-trasporto-alunni-disabili-presentazione-domande-contributo-entro-il-18-gennaio\/\" class=\"read-more\">Leggi Tutto &#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":76439,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-76438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fuori-provincia"],"_links":{"self":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/76438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/comments?post=76438"}],"version-history":[{"count":2,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/76438\/revisions"}],"predecessor-version":[{"id":76442,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/76438\/revisions\/76442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media\/76439"}],"wp:attachment":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media?parent=76438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/categories?post=76438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/tags?post=76438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}