{"id":76446,"date":"2022-12-28T09:12:00","date_gmt":"2022-12-28T08:12:00","guid":{"rendered":"https:\/\/www.siracusa2000.com\/?p=76446"},"modified":"2022-12-27T21:46:49","modified_gmt":"2022-12-27T20:46:49","slug":"scicli-imminente-il-nuovo-bando-per-laffidamento-della-gestione-del-cinema-teatro-italia","status":"publish","type":"post","link":"https:\/\/www.siracusa2000.com\/index.php\/2022\/12\/28\/scicli-imminente-il-nuovo-bando-per-laffidamento-della-gestione-del-cinema-teatro-italia\/","title":{"rendered":"Scicli. Imminente il nuovo bando per l&#8217;affidamento della gestione del Cinema Teatro Italia"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"541\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/12\/screenshot-234-1024x541.png\" alt=\"\" class=\"wp-image-76447\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/12\/screenshot-234-1024x541.png 1024w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/12\/screenshot-234-300x158.png 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/12\/screenshot-234-768x405.png 768w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/12\/screenshot-234.png 1040w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>E\u2019 ferma volont\u00e0 dell\u2019Amministrazione riaprire al pi\u00f9 presto il Cinema mettendo anche in calendario una prestigiosa stagione teatrale. <\/p>\n\n\n\n<p>Lo ribadisce il <strong>sindaco di Scicli, Mario Marino,<\/strong> annunciando la pubblicazione, ormai imminente, del nuovo bando per l\u2019affidamento della gestione del <strong>Cinema Teatro Italia.<\/strong><\/p>\n\n\n\n<p>Il bando sar\u00e0 rispondente alla nuova normativa sugli appalti e terr\u00e0 conto delle mutate esigenze del mercato della fruizione culturale.<\/p>\n\n\n\n<p>Il precedente contratto era in regime di prorogatio a causa della pandemia.<\/p>\n\n\n\n<p><em>(foto: il Cinema Teatro Italia nell\u2019omonima piazza a Scicli \u2013 immagine da googlemaps)<\/em><\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>\u00a9 Riproduzione riservata<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"926\" height=\"419\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend.png\" alt=\"\" class=\"wp-image-55152\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend.png 926w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend-300x136.png 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend-768x348.png 768w\" sizes=\"auto, (max-width: 926px) 100vw, 926px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>E\u2019 ferma volont\u00e0 dell\u2019Amministrazione riaprire al pi\u00f9 presto il Cinema mettendo anche in calendario una prestigiosa stagione teatrale. Lo ribadisce il sindaco di Scicli, Mario Marino, annunciando la pubblicazione, ormai imminente, del nuovo bando per l\u2019affidamento della gestione del Cinema <a href=\"https:\/\/www.siracusa2000.com\/index.php\/2022\/12\/28\/scicli-imminente-il-nuovo-bando-per-laffidamento-della-gestione-del-cinema-teatro-italia\/\" class=\"read-more\">Leggi Tutto &#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":76447,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-76446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fuori-provincia"],"_links":{"self":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/76446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/comments?post=76446"}],"version-history":[{"count":1,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/76446\/revisions"}],"predecessor-version":[{"id":76448,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/76446\/revisions\/76448"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media\/76447"}],"wp:attachment":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media?parent=76446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/categories?post=76446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/tags?post=76446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}