{"id":76504,"date":"2022-12-30T09:57:22","date_gmt":"2022-12-30T08:57:22","guid":{"rendered":"https:\/\/www.siracusa2000.com\/?p=76504"},"modified":"2022-12-30T09:57:23","modified_gmt":"2022-12-30T08:57:23","slug":"siracusa-truffa-dello-specchietto-ai-danni-di-un-anziano-scoperto-dalla-polizia-stradale","status":"publish","type":"post","link":"https:\/\/www.siracusa2000.com\/index.php\/2022\/12\/30\/siracusa-truffa-dello-specchietto-ai-danni-di-un-anziano-scoperto-dalla-polizia-stradale\/","title":{"rendered":"Siracusa. Truffa dello specchietto ai danni di un anziano, scoperto dalla Polizia Stradale"},"content":{"rendered":"\n<p>Attenti alla truffa dello specchietto. Sono anni che le forze dell\u2019ordine lo raccomandano, soprattutto, agli anziani, che rappresentano la preda preferita dei truffatori, eppure, qualcuno ci cade ancora.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"861\" height=\"408\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/12\/screenshot-250.png\" alt=\"\" class=\"wp-image-76505\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/12\/screenshot-250.png 861w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/12\/screenshot-250-300x142.png 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2022\/12\/screenshot-250-768x364.png 768w\" sizes=\"auto, (max-width: 861px) 100vw, 861px\" \/><\/figure>\n\n\n\n<p>E\u2019 successo qualche giorno fa, in una via del centro, a <strong>Siracusa,<\/strong> dove un automobilista 85enne, \u00e8 stato raggiunto e fermato da un\u2019altra auto, alla cui guida c\u2019era un 30enne, che aveva preteso il pagamento di una somma in denaro, sostenendo che l\u2019anziano gli avesse rotto lo specchietto retrovisore.<\/p>\n\n\n\n<p>La cosa non \u00e8 sfuggita a due operatori della <strong>Polizia Stradale<\/strong> i quali, avendo immediatamente, intuito quanto accaduto, si sono messi alla ricerca dei due mezzi ed hanno raggiunto i due protagonisti della scena. Per il 30enne non c\u2019\u00e8 stata, quindi, via di scampo ed \u00e8 stato<em> <\/em>deferito alla <strong>Procura della Repubblica di Siracusa<\/strong> per il reato di truffa aggravata.<\/p>\n\n\n\n<p><em>(foto: immagini fornite dalla Polizia Stradale di Siracusa)<\/em><\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>\u00a9 Riproduzione riservata<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"926\" height=\"419\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend.png\" alt=\"\" class=\"wp-image-55152\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend.png 926w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend-300x136.png 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend-768x348.png 768w\" sizes=\"auto, (max-width: 926px) 100vw, 926px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Attenti alla truffa dello specchietto. Sono anni che le forze dell\u2019ordine lo raccomandano, soprattutto, agli anziani, che rappresentano la preda preferita dei truffatori, eppure, qualcuno ci cade ancora. E\u2019 successo qualche giorno fa, in una via del centro, a Siracusa, <a href=\"https:\/\/www.siracusa2000.com\/index.php\/2022\/12\/30\/siracusa-truffa-dello-specchietto-ai-danni-di-un-anziano-scoperto-dalla-polizia-stradale\/\" class=\"read-more\">Leggi Tutto &#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":76505,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-76504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-citta"],"_links":{"self":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/76504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/comments?post=76504"}],"version-history":[{"count":3,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/76504\/revisions"}],"predecessor-version":[{"id":76508,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/76504\/revisions\/76508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media\/76505"}],"wp:attachment":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media?parent=76504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/categories?post=76504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/tags?post=76504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}