{"id":92104,"date":"2024-06-06T11:06:21","date_gmt":"2024-06-06T09:06:21","guid":{"rendered":"https:\/\/www.siracusa2000.com\/?p=92104"},"modified":"2024-06-06T11:06:22","modified_gmt":"2024-06-06T09:06:22","slug":"catania-dallemergenza-allurgenza-quarta-edizione-della-biennale-di-teatro-sociale","status":"publish","type":"post","link":"https:\/\/www.siracusa2000.com\/index.php\/2024\/06\/06\/catania-dallemergenza-allurgenza-quarta-edizione-della-biennale-di-teatro-sociale\/","title":{"rendered":"Catania. Dall&#8217;emergenza all&#8217;urgenza, quarta edizione della Biennale di Teatro Sociale"},"content":{"rendered":"\n<p>E\u2019 cominciato il contro alla rovescia per la quarta edizione della\u00a0<strong>Biennale di Teatro Sociale,<\/strong> autofinanziata da\u00a0<strong>Officina SocialMeccanica, che<\/strong> accoglie e potenzia lo stretto vincolo tra il teatro, gli individui, i gruppi e le intere comunit\u00e0, con particolare riferimento alle\u00a0fasce sociali a rischio di esclusione sociale.<strong>\u00a0<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"885\" height=\"559\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2024\/06\/PH_BiennaleTeatroSocialeCatania.jpeg\" alt=\"\" class=\"wp-image-92105\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2024\/06\/PH_BiennaleTeatroSocialeCatania.jpeg 885w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2024\/06\/PH_BiennaleTeatroSocialeCatania-300x189.jpeg 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2024\/06\/PH_BiennaleTeatroSocialeCatania-768x485.jpeg 768w\" sizes=\"auto, (max-width: 885px) 100vw, 885px\" \/><\/figure>\n\n\n\n<p>Il Festival si svolger\u00e0 il\u00a0<strong>14, 15 e 16 giugno a Catania<\/strong>\u00a0per offrire alla citt\u00e0 e al pubblico siciliano spazi e momenti di incontro, scambio, crescita. La tavola rotonda, in coprogettazione con il <strong>CSVE Centro dei Servizi per il Volontariato Etneo,<\/strong> i workshop e le performance, con la presenza di compagnie, formatori e studiosi del panorama nazionale, consentiranno l\u2019esplorazione di pratiche, dibattiti, riflessioni, visioni ed esperienze teatrali.<\/p>\n\n\n\n<p>\u201cL\u2019impegno dei volontari \u00e8 alla base del successo di questo Festival&#8221; \u2013 spiega\u00a0<strong>Mariagiovanna Italia<\/strong>, fondatrice di <strong>Officina SocialMeccanica <\/strong>\u2013 \u201cabbiamo costruito una rete che valicasse i confini della nostra citt\u00e0 e della nostra regione, tessendo connessioni tra diverse realt\u00e0 teatrali impegnate nel percorso di sviluppo delle comunit\u00e0\u201d.<\/p>\n\n\n\n<p>Il programma del Festival coinvolge gruppi teatrali, operatori di Teatro Sociale, ricercatori, formatori impegnati nel territorio siciliano e nazionale.\u00a0<\/p>\n\n\n\n<p>Per sostenere la <strong>Biennale di Teatro Sociale<\/strong> per la prima volta \u00e8 possibile contribuire tramite il\u00a0crowdfunding\u00a0<a href=\"https:\/\/www.produzionidalbasso.com\/project\/iv-biennale-di-teatro-sociale\" target=\"_blank\" rel=\"noreferrer noopener\">( clicca qui )<\/a>. <\/p>\n\n\n\n<p><em>(foto: immagine fornita dagli organizzatori)<\/em><\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>\u00a9 Riproduzione riservata<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"926\" height=\"419\" src=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend.png\" alt=\"\" class=\"wp-image-55152\" srcset=\"https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend.png 926w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend-300x136.png 300w, https:\/\/www.siracusa2000.com\/wp-content\/uploads\/2021\/04\/banner-meteo-weekend-768x348.png 768w\" sizes=\"auto, (max-width: 926px) 100vw, 926px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>E\u2019 cominciato il contro alla rovescia per la quarta edizione della\u00a0Biennale di Teatro Sociale, autofinanziata da\u00a0Officina SocialMeccanica, che accoglie e potenzia lo stretto vincolo tra il teatro, gli individui, i gruppi e le intere comunit\u00e0, con particolare riferimento alle\u00a0fasce sociali <a href=\"https:\/\/www.siracusa2000.com\/index.php\/2024\/06\/06\/catania-dallemergenza-allurgenza-quarta-edizione-della-biennale-di-teatro-sociale\/\" class=\"read-more\">Leggi Tutto &#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":92105,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-92104","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fuori-provincia"],"_links":{"self":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/92104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/comments?post=92104"}],"version-history":[{"count":1,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/92104\/revisions"}],"predecessor-version":[{"id":92106,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/posts\/92104\/revisions\/92106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media\/92105"}],"wp:attachment":[{"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/media?parent=92104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/categories?post=92104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.siracusa2000.com\/index.php\/wp-json\/wp\/v2\/tags?post=92104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}